{"id":3282,"date":"2007-08-27T13:21:44","date_gmt":"2007-08-27T19:21:44","guid":{"rendered":"http:\/\/impeachforpeace.org\/impeach_bush_blog\/?p=3282"},"modified":"2017-05-21T03:07:16","modified_gmt":"2017-05-21T09:07:16","slug":"gonzo-gonzo-now-impeach-cheney","status":"publish","type":"post","link":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/","title":{"rendered":"VICTORY! Gonzo Gonzo, NOW Impeach Cheney"},"content":{"rendered":"<p><img decoding=\"async\" style='float: left; margin: 0px 15px 15px 0px; width: 250px;' src=\"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2007\/08\/impeachmobile-bruce.JPG\" alt=\"impeachmobile-bruce.JPG\" \/><br \/>\nMinneapolis <i>Veteran&#8217;s for Peace<\/i> and Justice through Impeachment Activist Bruce Berry has the coolest Art Car in America. We hope he finds lots of reasons to drive this car all over St. Paul during the war profiteer rally and party also called the GOP Convention. Anyone else interested in painting up a vehicle? I&#8217;ve got one to donate.<\/p>\n<p>~ Mikael<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minneapolis Veteran&#8217;s for Peace and Justice through Impeachment Activist Bruce Berry has the coolest Art Car in America. We hope he finds lots of reasons to drive this car all over St. Paul during the war profiteer rally and party also called the GOP Convention. Anyone else interested in painting up a vehicle? I&#8217;ve got&#8230;<\/p>\n","protected":false},"author":3,"featured_media":3281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[122,2,21],"tags":[],"class_list":["post-3282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bush_era","category-impeachment-events","category-minnesota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VICTORY! Gonzo Gonzo, NOW Impeach Cheney &#8226; Impeach for Peace<\/title>\n<meta name=\"description\" content=\"Citizen&#039;s impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/\"},\"author\":{\"name\":\"Mikael\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/017c7f3b977bf6d39b54433e71d0d3b1\"},\"headline\":\"VICTORY! Gonzo Gonzo, NOW Impeach Cheney\",\"datePublished\":\"2007-08-27T19:21:44+00:00\",\"dateModified\":\"2017-05-21T09:07:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/\"},\"wordCount\":67,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/impeachmobile-bruce.JPG\",\"articleSection\":[\"Bush Era\",\"Impeachment Events\",\"Minnesota\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/\",\"name\":\"VICTORY! Gonzo Gonzo, NOW Impeach Cheney &#8226; Impeach for Peace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/impeachmobile-bruce.JPG\",\"datePublished\":\"2007-08-27T19:21:44+00:00\",\"dateModified\":\"2017-05-21T09:07:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/017c7f3b977bf6d39b54433e71d0d3b1\"},\"description\":\"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2007\\\/08\\\/gonzo-gonzo-now-impeach-cheney\\\/#primaryimage\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/impeachmobile-bruce.JPG\",\"contentUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/impeachmobile-bruce.JPG\",\"width\":480,\"height\":360},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/\",\"name\":\"Impeach for Peace\",\"description\":\"Citizen Impeachment Tool\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/017c7f3b977bf6d39b54433e71d0d3b1\",\"name\":\"Mikael\",\"sameAs\":[\"http:\\\/\\\/impeachforpeace.org\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/author\\\/mikael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VICTORY! Gonzo Gonzo, NOW Impeach Cheney &#8226; Impeach for Peace","description":"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#article","isPartOf":{"@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/"},"author":{"name":"Mikael","@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/017c7f3b977bf6d39b54433e71d0d3b1"},"headline":"VICTORY! Gonzo Gonzo, NOW Impeach Cheney","datePublished":"2007-08-27T19:21:44+00:00","dateModified":"2017-05-21T09:07:16+00:00","mainEntityOfPage":{"@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/"},"wordCount":67,"commentCount":0,"image":{"@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#primaryimage"},"thumbnailUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2007\/08\/impeachmobile-bruce.JPG","articleSection":["Bush Era","Impeachment Events","Minnesota"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/","url":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/","name":"VICTORY! Gonzo Gonzo, NOW Impeach Cheney &#8226; Impeach for Peace","isPartOf":{"@id":"https:\/\/impeachforpeace.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#primaryimage"},"image":{"@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#primaryimage"},"thumbnailUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2007\/08\/impeachmobile-bruce.JPG","datePublished":"2007-08-27T19:21:44+00:00","dateModified":"2017-05-21T09:07:16+00:00","author":{"@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/017c7f3b977bf6d39b54433e71d0d3b1"},"description":"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/impeachforpeace.org\/blog\/2007\/08\/gonzo-gonzo-now-impeach-cheney\/#primaryimage","url":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2007\/08\/impeachmobile-bruce.JPG","contentUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2007\/08\/impeachmobile-bruce.JPG","width":480,"height":360},{"@type":"WebSite","@id":"https:\/\/impeachforpeace.org\/blog\/#website","url":"https:\/\/impeachforpeace.org\/blog\/","name":"Impeach for Peace","description":"Citizen Impeachment Tool","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/impeachforpeace.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/017c7f3b977bf6d39b54433e71d0d3b1","name":"Mikael","sameAs":["http:\/\/impeachforpeace.org\/blog\/"],"url":"https:\/\/impeachforpeace.org\/blog\/author\/mikael\/"}]}},"_links":{"self":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts\/3282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/comments?post=3282"}],"version-history":[{"count":0,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts\/3282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/media\/3281"}],"wp:attachment":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/media?parent=3282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/categories?post=3282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/tags?post=3282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}