{"id":7361,"date":"2016-12-01T15:52:05","date_gmt":"2016-12-01T21:52:05","guid":{"rendered":"http:\/\/impeachforpeace.org\/impeach_bush_blog\/?p=7361"},"modified":"2018-12-21T13:47:44","modified_gmt":"2018-12-21T19:47:44","slug":"president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business","status":"publish","type":"post","link":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/","title":{"rendered":"White House counsel for President Bush warns: Trump impeached the second he takes office"},"content":{"rendered":"<p><a href=\"https:\/\/www.google.com\/amp\/s\/heatst.com\/politics\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/amp\/?client=ms-android-hms-tmobile-us\"><img decoding=\"async\" style='float: left; margin: 0px 15px 15px 0px; width: 250px;' src=\"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2016\/12\/raheem-1.jpg\" alt=\"\" width=\"200\" align=\"left\" \/><\/a><\/p>\n<blockquote><p>The President-Elected responded to charges of violating the Emoluments Clause. Is it enough?<\/p><\/blockquote>\n<p>The <a href=\"https:\/\/www.heritage.org\/constitution\/#%21\/articles\/1\/essays\/68\/emoluments-clause\" target=\"_top\">Emoluments Clause<\/a> in the Constitution bars any President from deriving financial advantage for their personal businesses, or for themselves. Democrats and democratic lawyers, as well as a former <a href=\"http:\/\/www.cnn.com\/2016\/11\/16\/opinions\/trump-potential-conflicts-interest-painter\/\" target=\"_top\">White House counsel for President Bush<\/a>, had warned that Trump could be impeached the second he took the oath of office if he had not separated himself from his business interests.<\/p>\n<p>Continue reading: <em><a href=\"https:\/\/heatst.com\/politics\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/\">White House counsel for President Bush, warns Trump impeached the second he takes office<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The President-Elected responded to charges of violating the Emoluments Clause. Is it enough? The Emoluments Clause in the Constitution bars any President from deriving financial advantage for their personal businesses, or for themselves. Democrats and democratic lawyers, as well as a former White House counsel for President Bush, had warned that Trump could be impeached&#8230;<\/p>\n","protected":false},"author":2312,"featured_media":7362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7],"tags":[125,124,76,123,107,127,126,106,105,77],"class_list":["post-7361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impeachment-evidence","tag-calltoaction","tag-dumptrump","tag-impeach","tag-impeachtrump","tag-muslimban","tag-nofascistusa","tag-potus","tag-resist","tag-theresistance","tag-trump"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>White House counsel for President Bush warns: Trump impeached the second he takes office &#8226; Impeach for Peace<\/title>\n<meta name=\"description\" content=\"Citizen&#039;s impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/\"},\"author\":{\"name\":\"Boxes Rocks\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/149ba95c6f2defa16d41ab16c8b52734\"},\"headline\":\"White House counsel for President Bush warns: Trump impeached the second he takes office\",\"datePublished\":\"2016-12-01T21:52:05+00:00\",\"dateModified\":\"2018-12-21T19:47:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/\"},\"wordCount\":103,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/raheem-1.jpg\",\"keywords\":[\"CalltoAction\",\"dumpTrump\",\"Impeach\",\"ImpeachTrump\",\"MuslimBan\",\"NoFascistUSA\",\"POTUS\",\"resist\",\"theResistance\",\"Trump\"],\"articleSection\":[\"Impeachment Evidence\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/\",\"name\":\"White House counsel for President Bush warns: Trump impeached the second he takes office &#8226; Impeach for Peace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/raheem-1.jpg\",\"datePublished\":\"2016-12-01T21:52:05+00:00\",\"dateModified\":\"2018-12-21T19:47:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/149ba95c6f2defa16d41ab16c8b52734\"},\"description\":\"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/2016\\\/12\\\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\\\/#primaryimage\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/raheem-1.jpg\",\"contentUrl\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/raheem-1.jpg\",\"width\":871,\"height\":653},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/\",\"name\":\"Impeach for Peace\",\"description\":\"Citizen Impeachment Tool\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/#\\\/schema\\\/person\\\/149ba95c6f2defa16d41ab16c8b52734\",\"name\":\"Boxes Rocks\",\"url\":\"https:\\\/\\\/impeachforpeace.org\\\/blog\\\/author\\\/ifp2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"White House counsel for President Bush warns: Trump impeached the second he takes office &#8226; Impeach for Peace","description":"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#article","isPartOf":{"@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/"},"author":{"name":"Boxes Rocks","@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/149ba95c6f2defa16d41ab16c8b52734"},"headline":"White House counsel for President Bush warns: Trump impeached the second he takes office","datePublished":"2016-12-01T21:52:05+00:00","dateModified":"2018-12-21T19:47:44+00:00","mainEntityOfPage":{"@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/"},"wordCount":103,"commentCount":0,"image":{"@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#primaryimage"},"thumbnailUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2016\/12\/raheem-1.jpg","keywords":["CalltoAction","dumpTrump","Impeach","ImpeachTrump","MuslimBan","NoFascistUSA","POTUS","resist","theResistance","Trump"],"articleSection":["Impeachment Evidence"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/","url":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/","name":"White House counsel for President Bush warns: Trump impeached the second he takes office &#8226; Impeach for Peace","isPartOf":{"@id":"https:\/\/impeachforpeace.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#primaryimage"},"image":{"@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#primaryimage"},"thumbnailUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2016\/12\/raheem-1.jpg","datePublished":"2016-12-01T21:52:05+00:00","dateModified":"2018-12-21T19:47:44+00:00","author":{"@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/149ba95c6f2defa16d41ab16c8b52734"},"description":"Citizen's impeach strategy. Rules of Congress say citizens can initiate. Once it was used 2 impeach a federal judge.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/impeachforpeace.org\/blog\/2016\/12\/president-elect-donald-trump-addresses-emoluments-clause-promises-to-leave-his-business\/#primaryimage","url":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2016\/12\/raheem-1.jpg","contentUrl":"https:\/\/impeachforpeace.org\/blog\/wp-content\/uploads\/2016\/12\/raheem-1.jpg","width":871,"height":653},{"@type":"WebSite","@id":"https:\/\/impeachforpeace.org\/blog\/#website","url":"https:\/\/impeachforpeace.org\/blog\/","name":"Impeach for Peace","description":"Citizen Impeachment Tool","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/impeachforpeace.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/impeachforpeace.org\/blog\/#\/schema\/person\/149ba95c6f2defa16d41ab16c8b52734","name":"Boxes Rocks","url":"https:\/\/impeachforpeace.org\/blog\/author\/ifp2\/"}]}},"_links":{"self":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts\/7361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/users\/2312"}],"replies":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/comments?post=7361"}],"version-history":[{"count":1,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts\/7361\/revisions"}],"predecessor-version":[{"id":23796,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/posts\/7361\/revisions\/23796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/media\/7362"}],"wp:attachment":[{"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/media?parent=7361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/categories?post=7361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/impeachforpeace.org\/blog\/wp-json\/wp\/v2\/tags?post=7361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}